{"id":23783,"date":"2022-04-24T15:05:00","date_gmt":"2022-04-24T15:05:00","guid":{"rendered":"http:\/\/datest.me\/?post_type=cpt_services&#038;p=23783"},"modified":"2025-12-26T14:18:18","modified_gmt":"2025-12-26T14:18:18","slug":"equipment","status":"publish","type":"cpt_services","link":"https:\/\/datest.me\/hk\/services\/equipment\/","title":{"rendered":"For International Students"},"content":{"rendered":"<h5 class=\"wp-block-heading\">Sed ut perspiciatis unde omnis iste natus et<\/h5>\n\n\n\n<p>Lorem ipsum dolor sit amet, consetetur sadipscing elitr, sed diam nonumy eirmod tempor invidunt ut labore et dolore magna aliquyam erat, sed diam voluptua. At vero eos et accusam et justo duo dolores et ea rebum. Stet clita kasd gubergren, no sea takimata sanctus est Lorem ipsum dolor sit amet.<\/p>\n\n\n\n<p>Aliquam laoreet sed neque ac vehicula. Cras congue eros nec quam laoreet, in viverra erat bibendum. Cras turpis urna, vulputate at est vitae, posuere lobortis erat.<\/p>\n\n\n\n<div style=\"height:20px\" aria-hidden=\"true\" class=\"wp-block-spacer extra_tiny_spacer\"><\/div>\n\n\n\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-1 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><img fetchpriority=\"high\" decoding=\"async\" width=\"1024\" height=\"683\" data-id=\"25467\" src=\"http:\/\/datest.me\/wp-content\/uploads\/2020\/05\/image-38-copyright-1024x683.jpg\" alt=\"\" class=\"wp-image-25467\" srcset=\"https:\/\/datest.me\/wp-content\/uploads\/2020\/05\/image-38-copyright-1024x683.jpg 1024w, https:\/\/datest.me\/wp-content\/uploads\/2020\/05\/image-38-copyright-300x200.jpg 300w, https:\/\/datest.me\/wp-content\/uploads\/2020\/05\/image-38-copyright-768x512.jpg 768w, https:\/\/datest.me\/wp-content\/uploads\/2020\/05\/image-38-copyright-1536x1024.jpg 1536w, https:\/\/datest.me\/wp-content\/uploads\/2020\/05\/image-38-copyright-370x247.jpg 370w, https:\/\/datest.me\/wp-content\/uploads\/2020\/05\/image-38-copyright-840x560.jpg 840w, https:\/\/datest.me\/wp-content\/uploads\/2020\/05\/image-38-copyright-410x273.jpg 410w, https:\/\/datest.me\/wp-content\/uploads\/2020\/05\/image-38-copyright-600x400.jpg 600w, https:\/\/datest.me\/wp-content\/uploads\/2020\/05\/image-38-copyright.jpg 1920w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" width=\"1024\" height=\"683\" data-id=\"25487\" src=\"http:\/\/datest.me\/wp-content\/uploads\/2022\/10\/image-36-copyright-1024x683.jpg\" alt=\"\" class=\"wp-image-25487\" srcset=\"https:\/\/datest.me\/wp-content\/uploads\/2022\/10\/image-36-copyright-1024x683.jpg 1024w, https:\/\/datest.me\/wp-content\/uploads\/2022\/10\/image-36-copyright-300x200.jpg 300w, https:\/\/datest.me\/wp-content\/uploads\/2022\/10\/image-36-copyright-768x512.jpg 768w, https:\/\/datest.me\/wp-content\/uploads\/2022\/10\/image-36-copyright-1536x1025.jpg 1536w, https:\/\/datest.me\/wp-content\/uploads\/2022\/10\/image-36-copyright-370x247.jpg 370w, https:\/\/datest.me\/wp-content\/uploads\/2022\/10\/image-36-copyright-840x560.jpg 840w, https:\/\/datest.me\/wp-content\/uploads\/2022\/10\/image-36-copyright-410x274.jpg 410w, https:\/\/datest.me\/wp-content\/uploads\/2022\/10\/image-36-copyright-600x400.jpg 600w, https:\/\/datest.me\/wp-content\/uploads\/2022\/10\/image-36-copyright.jpg 1920w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n<\/figure>\n\n\n\n<p>Lorem ipsum dolor sit amet, consetetur sadipscing elitr, sed diam nonumy eirmod tempor invidunt ut labore et dolore magna aliquyam erat, sed diam voluptua. At vero eos et accusam et justo duo dolores et ea rebum. Stet clita kasd gubergren, no sea takimata sanctus est Lorem ipsum dolor sit amet.<\/p>\n\n\n\n<h5 class=\"wp-block-heading\">Aliquam quis lobortis quam<\/h5>\n\n\n\n<p>Curabitur pellentesque odio magna, id malesuada arcu sodales ut. Sed sed quam ut ex bibendum commodo id id magna. Aliquam sed ligula sed ante blandit volutpat. Ut bibendum, nisi et mattis vulputate, odio arcu aliquet metus, nec dapibus risus risus quis lectus.<\/p>\n\n\n\n<p>Lorem ipsum dolor sit amet, consetetur sadipscing elitr, sed diam nonumy eirmod tempor invidunt ut labore et dolore magna aliquyam erat, sed diam voluptua. At vero eos et accusam et justo duo dolores et ea rebum. Stet clita kasd gubergren, no sea takimata sanctus est Lorem ipsum dolor sit amet. <\/p>\n\n\n\n<div style=\"height:20px\" aria-hidden=\"true\" class=\"wp-block-spacer tiny_spacer\"><\/div>\n\n\n<div class=\"widget_area sc_widget_video\"><aside class=\"widget widget_video\"><div id=\"sc_video_882946235\" class=\"trx_addons_video_player with_cover hover_play\"><img decoding=\"async\" src=\"https:\/\/datest.me\/wp-content\/uploads\/2023\/03\/image-16-copyright-840x473.jpg\" alt=\"Video cover\" width=\"840\" height=\"473\"><div class=\"video_mask\"><\/div><div class=\"video_hover\" data-video=\"&lt;iframe allow=&quot;autoplay&quot; src=&quot;https:\/\/player.vimeo.com\/video\/299726198?h=&amp;autoplay=1&quot; width=&quot;720&quot; height=&quot;405&quot;&gt;&lt;\/iframe&gt;\"><\/div><div class=\"video_embed video_frame\"><\/div><\/div><\/aside><\/div>\n\n\n<div style=\"height:100px\" aria-hidden=\"true\" class=\"wp-block-spacer small_spacer\"><\/div>\n\n\n\n<p>At vero eos et accusam et justo duo dolores et ea rebum. Stet clita kasd gubergren, no sea takimata sanctus est Lorem ipsum dolor sit amet. Lorem ipsum dolor sit amet, consetetur sadipscing elitr, sed diam nonumy eirmod tempor invidunt ut labore et dolore magna aliquyam erat, sed diam voluptua. At vero eos et accusam et justo duo dolores et ea rebum. Stet clita kasd gubergren, no sea takimata sanctus est Lorem ipsum dolor sit amet. Lorem ipsum dolor sit amet, consetetur sadipscing elitr.<\/p>","protected":false},"excerpt":{"rendered":"<p>Sed ut perspiciatis unde omnis iste natus et Lorem ipsum dolor sit amet, consetetur sadipscing elitr, sed diam nonumy eirmod tempor invidunt ut labore et dolore magna aliquyam erat, sed&hellip;<\/p>","protected":false},"author":1,"featured_media":25896,"comment_status":"closed","ping_status":"closed","template":"","cpt_services_group":[28],"class_list":["post-23783","cpt_services","type-cpt_services","status-publish","has-post-thumbnail","hentry","cpt_services_group-what-we-do"],"_links":{"self":[{"href":"https:\/\/datest.me\/hk\/wp-json\/wp\/v2\/cpt_services\/23783","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/datest.me\/hk\/wp-json\/wp\/v2\/cpt_services"}],"about":[{"href":"https:\/\/datest.me\/hk\/wp-json\/wp\/v2\/types\/cpt_services"}],"author":[{"embeddable":true,"href":"https:\/\/datest.me\/hk\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/datest.me\/hk\/wp-json\/wp\/v2\/comments?post=23783"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/datest.me\/hk\/wp-json\/wp\/v2\/media\/25896"}],"wp:attachment":[{"href":"https:\/\/datest.me\/hk\/wp-json\/wp\/v2\/media?parent=23783"}],"wp:term":[{"taxonomy":"cpt_services_group","embeddable":true,"href":"https:\/\/datest.me\/hk\/wp-json\/wp\/v2\/cpt_services_group?post=23783"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}